{"id":14605,"date":"2024-09-06T21:21:10","date_gmt":"2024-09-06T21:21:10","guid":{"rendered":"http:\/\/maxxinstitutes.com\/apartamentos-compartidos\/"},"modified":"2025-09-24T17:24:48","modified_gmt":"2025-09-24T17:24:48","slug":"apartamentos-compartidos","status":"publish","type":"page","link":"https:\/\/maxxinstitutes.com\/es\/apartamentos-compartidos\/","title":{"rendered":"Apartamentos compartidos"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"14605\" class=\"elementor elementor-14605 elementor-88\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-00d9e23 elementor-reverse-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"00d9e23\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-cd1f262\" data-id=\"cd1f262\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9cd8faa elementor-widget elementor-widget-heading\" data-id=\"9cd8faa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Apartamentos compartidos para estudiantes<br> <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-66f4bc6 color-scheme-inherit text-left elementor-widget elementor-widget-text-editor\" data-id=\"66f4bc6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Si prefieres un estilo de vida independiente y quieres sumergirte de lleno en la vida estudiantil, un piso compartido es la opci\u00f3n perfecta para ti. Ofrecemos tres pisos compartidos diferentes <\/p><p><em><strong>&#8211; Espa\u00f1a M\u00eda &#8211; San Vicente &#8211; Mi Extremadura<\/strong><\/em><\/p><p><a href=\"#\"><strong>Caracter\u00edsticas del apartamento:<\/strong><\/a><\/p><p>&#8211; Cocina totalmente equipada<br>&#8211; De 1 a 3 duchas<br>&#8211; Wi-Fi incluido<br><a href=\"#\">&#8211; <strong>Limpieza:<\/strong> <\/a>Las zonas comunes y las duchas se limpian 1 vez por semana. Ser\u00e1s responsable de limpiar tu propia habitaci\u00f3n y de mantener limpias la cocina y las duchas. <br><a href=\"#\">&#8211; <strong>Tus compa\u00f1eros de piso:<\/strong><\/a> Nuestros estudiantes proceden de varios pa\u00edses y tienen edades comprendidas entre los 18 y los 70 a\u00f1os. Elegir un piso compartido te permite relacionarte con tus compa\u00f1eros y ampliar tus horizontes interculturales. <br>&#8211; <a href=\"#\"> <strong>Disponibilidad<\/strong><\/a> Ten en cuenta que durante los meses de verano (de junio a septiembre), la disponibilidad es limitada. Ponte en contacto con nosotros con antelaci\u00f3n para asegurarte la disponibilidad del tipo de habitaci\u00f3n que prefieras. <br><a href=\"#\">&#8211; <strong>Dep\u00f3sito de da\u00f1os:<\/strong><\/a> A tu llegada, deber\u00e1s abonar una fianza de 150 euros. Se puede congelar autom\u00e1ticamente en tu tarjeta de cr\u00e9dito o pagar en efectivo. La fianza se reembolsar\u00e1 al final de tu estancia si no se producen da\u00f1os y se devuelve la llave.  <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8028ccf elementor-align-left elementor-mobile-align-left elementor-widget elementor-widget-button\" data-id=\"8028ccf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"http:\/\/maxxinstitutes.com\/cost-calculator\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-long-arrow-alt-right\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M313.941 216H12c-6.627 0-12 5.373-12 12v56c0 6.627 5.373 12 12 12h301.941v46.059c0 21.382 25.851 32.09 40.971 16.971l86.059-86.059c9.373-9.373 9.373-24.569 0-33.941l-86.059-86.059c-15.119-15.119-40.971-4.411-40.971 16.971V216z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">CALCULA TU PRECIO<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-c559904\" data-id=\"c559904\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-534c662 elementor-widget elementor-widget-image\" data-id=\"534c662\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"522\" height=\"608\" src=\"https:\/\/maxxinstitutes.com\/wp-content\/uploads\/2024\/10\/Tabel.jpg\" class=\"attachment-full size-full wp-image-14322\" alt=\"\" srcset=\"https:\/\/maxxinstitutes.com\/wp-content\/uploads\/2024\/10\/Tabel.jpg 522w, https:\/\/maxxinstitutes.com\/wp-content\/uploads\/2024\/10\/Tabel-258x300.jpg 258w, https:\/\/maxxinstitutes.com\/wp-content\/uploads\/2024\/10\/Tabel-150x175.jpg 150w\" sizes=\"(max-width: 522px) 100vw, 522px\" title=\"\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-c1de51b e-con-full e-flex e-con e-parent\" data-id=\"c1de51b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-1e2eaa0 e-con-full e-flex e-con e-child\" data-id=\"1e2eaa0\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b614c18 elementor-align-start elementor-mobile-align-start elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"b614c18\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-bed\" viewBox=\"0 0 640 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M176 256c44.11 0 80-35.89 80-80s-35.89-80-80-80-80 35.89-80 80 35.89 80 80 80zm352-128H304c-8.84 0-16 7.16-16 16v144H64V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v352c0 8.84 7.16 16 16 16h32c8.84 0 16-7.16 16-16v-48h512v48c0 8.84 7.16 16 16 16h32c8.84 0 16-7.16 16-16V240c0-61.86-50.14-112-112-112z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Cama individual o cama m\u00e1s grande disponible<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-user-friends\" viewBox=\"0 0 640 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M192 256c61.9 0 112-50.1 112-112S253.9 32 192 32 80 82.1 80 144s50.1 112 112 112zm76.8 32h-8.3c-20.8 10-43.9 16-68.5 16s-47.6-6-68.5-16h-8.3C51.6 288 0 339.6 0 403.2V432c0 26.5 21.5 48 48 48h288c26.5 0 48-21.5 48-48v-28.8c0-63.6-51.6-115.2-115.2-115.2zM480 256c53 0 96-43 96-96s-43-96-96-96-96 43-96 96 43 96 96 96zm48 32h-3.8c-13.9 4.8-28.6 8-44.2 8s-30.3-3.2-44.2-8H432c-20.4 0-39.2 5.9-55.7 15.4 24.4 26.3 39.7 61.2 39.7 99.8v38.4c0 2.2-.5 4.3-.6 6.4H592c26.5 0 48-21.5 48-48 0-61.9-50.1-112-112-112z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Los pisos compartidos s\u00f3lo est\u00e1n disponibles para los alumnos de la escuela.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-utensil-spoon\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M480.1 31.9c-55-55.1-164.9-34.5-227.8 28.5-49.3 49.3-55.1 110-28.8 160.4L9 413.2c-11.6 10.5-12.1 28.5-1 39.5L59.3 504c11 11 29.1 10.5 39.5-1.1l192.4-214.4c50.4 26.3 111.1 20.5 160.4-28.8 63-62.9 83.6-172.8 28.5-227.8z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Cocina totalmente equipada en cada apartamento<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6f96301 e-con-full e-flex e-con e-child\" data-id=\"6f96301\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ce599ae elementor-align-start elementor-mobile-align-start elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"ce599ae\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-bath\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M32,384a95.4,95.4,0,0,0,32,71.09V496a16,16,0,0,0,16,16h32a16,16,0,0,0,16-16V480H384v16a16,16,0,0,0,16,16h32a16,16,0,0,0,16-16V455.09A95.4,95.4,0,0,0,480,384V336H32ZM496,256H80V69.25a21.26,21.26,0,0,1,36.28-15l19.27,19.26c-13.13,29.88-7.61,59.11,8.62,79.73l-.17.17A16,16,0,0,0,144,176l11.31,11.31a16,16,0,0,0,22.63,0L283.31,81.94a16,16,0,0,0,0-22.63L272,48a16,16,0,0,0-22.62,0l-.17.17c-20.62-16.23-49.83-21.75-79.73-8.62L150.22,20.28A69.25,69.25,0,0,0,32,69.25V256H16A16,16,0,0,0,0,272v16a16,16,0,0,0,16,16H496a16,16,0,0,0,16-16V272A16,16,0,0,0,496,256Z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">2 o m\u00e1ximo 3 estudiantes comparten un ba\u00f1o<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-map-marker-alt\" viewBox=\"0 0 384 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M172.268 501.67C26.97 291.031 0 269.413 0 192 0 85.961 85.961 0 192 0s192 85.961 192 192c0 77.413-26.97 99.031-172.268 309.67-9.535 13.774-29.93 13.773-39.464 0zM192 272c44.183 0 80-35.817 80-80s-35.817-80-80-80-80 35.817-80 80 35.817 80 80 80z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">A 3-15 minutos a pie de la escuela<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-user-shield\" viewBox=\"0 0 640 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M622.3 271.1l-115.2-45c-4.1-1.6-12.6-3.7-22.2 0l-115.2 45c-10.7 4.2-17.7 14-17.7 24.9 0 111.6 68.7 188.8 132.9 213.9 9.6 3.7 18 1.6 22.2 0C558.4 489.9 640 420.5 640 296c0-10.9-7-20.7-17.7-24.9zM496 462.4V273.3l95.5 37.3c-5.6 87.1-60.9 135.4-95.5 151.8zM224 256c70.7 0 128-57.3 128-128S294.7 0 224 0 96 57.3 96 128s57.3 128 128 128zm96 40c0-2.5.8-4.8 1.1-7.2-2.5-.1-4.9-.8-7.5-.8h-16.7c-22.2 10.2-46.9 16-72.9 16s-50.6-5.8-72.9-16h-16.7C60.2 288 0 348.2 0 422.4V464c0 26.5 21.5 48 48 48h352c6.8 0 13.3-1.5 19.2-4-54-42.9-99.2-116.7-99.2-212z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">M\u00ednimo 18 - Media de 25 a 65 a\u00f1os<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8dafa77 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8dafa77\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-0347bac\" data-id=\"0347bac\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7fe4dde elementor-widget elementor-widget-video\" data-id=\"7fe4dde\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/youtu.be\\\/3SeMMgIUjZs?si=sKGFLvPZ_RD0KXyx&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-41391e7\" data-id=\"41391e7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-425ec6f elementor-widget elementor-widget-heading\" data-id=\"425ec6f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Espa\u00f1a M\u00eda\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-566f54a color-scheme-inherit text-left elementor-widget elementor-widget-text-editor\" data-id=\"566f54a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li><strong>Ubicaci\u00f3n:<\/strong> A un m\u00e1ximo de 10 minutos a pie de la escuela;<\/li><li><strong>Tipos de habitaciones:<\/strong> 3x habitaciones individuales y 2x una habitaci\u00f3n doble tambi\u00e9n disponible para uso individual;<\/li><li><strong>Cuarto de ba\u00f1o:<\/strong> 2 cuartos de ba\u00f1o compartidos (1 con ducha y 2 aseos, 1 con ducha y 1 aseo;<\/li><li><strong>Lavander\u00eda:<\/strong> Uso de lavadora incluido (detergentes propios);<\/li><li><strong>Limpieza:<\/strong> Limpieza de la habitaci\u00f3n al hacer el check-in, no se incluye el servicio de limpieza. Las zonas comunes y la habitaci\u00f3n ser\u00e1n limpiadas por los compa\u00f1eros de piso; <\/li><li><strong>Ropa de cama:<\/strong> Se proporcionan s\u00e1banas y toallas (no toallas de playa);<\/li><li><strong>Cocina:<\/strong> Cocina totalmente equipada, de uso compartido;<\/li><li><strong>Comidas:<\/strong> Sin comidas;<\/li><li><strong>Internet:<\/strong> Mediante Wi-fi incluido;<\/li><li><strong>Llave:<\/strong> A recoger en la escuela a tu llegada (a cualquier hora, 24h\/d\u00eda);<\/li><li><strong>Edades:<\/strong> De 18 a 70 a\u00f1os aproximadamente, sexo mixto; <\/li><li><strong>Facturas:<\/strong> Incluidas (internet, agua, electricidad, etc.);<\/li><li><strong>Facturaci\u00f3n: <\/strong>Normalmente los domingos despu\u00e9s de las 18:00 (posibilidad de dejar el equipaje antes). Noches extra disponibles; <\/li><li><strong>Salida:<\/strong> Normalmente los s\u00e1bados antes de las 11:00 (posibilidad de dejar el equipaje para salidas posteriores). Noches extra disponibles. <\/li><li><strong>Distancia al aeropuerto:<\/strong> Aprox.10 minutos en taxi y 20 minutos en autob\u00fas;<\/li><li><strong>Transporte p\u00fablico:<\/strong> A unos 15 minutos a pie de la estaci\u00f3n central de autobuses; <\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b938a57 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b938a57\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-3ea31a6\" data-id=\"3ea31a6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0c20571 elementor-widget elementor-widget-video\" data-id=\"0c20571\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/www.youtube.com\\\/watch?si=aXHKs2K2oE8oDY4C&amp;v=wMw4JWqM0Q0&amp;feature=youtu.be&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-6837c0b\" data-id=\"6837c0b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6ed20e1 elementor-widget elementor-widget-heading\" data-id=\"6ed20e1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Mi Extremadura\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a55d814 color-scheme-inherit text-left elementor-widget elementor-widget-text-editor\" data-id=\"a55d814\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li><strong>Ubicaci\u00f3n:<\/strong> A un m\u00e1ximo de 10 minutos a pie de la escuela;<\/li><li><strong>Distancia al aeropuerto:<\/strong> Aprox.10 minutos en taxi y 20 minutos en autob\u00fas;<\/li><li><strong>Transporte p\u00fablico:<\/strong> A unos 15 minutos a pie de la estaci\u00f3n central de autobuses; <\/li><li><strong>Habitaciones: <\/strong>1x habitaci\u00f3n individual con cama m\u00e1s peque\u00f1a y sin balc\u00f3n, 4x habitaciones individuales con cama m\u00e1s grande y con balc\u00f3n;<\/li><li><strong>Cuarto de ba\u00f1o:<\/strong> 1x ba\u00f1o compartido con 2 duchas separadas y 2 WC,1x ba\u00f1o compartido con 1 ducha y 1 WC;<\/li><li><strong>Lavander\u00eda:<\/strong> Uso de lavadora incluido (detergentes propios);<\/li><li><strong>Limpieza:<\/strong> Limpieza de la habitaci\u00f3n al hacer el check-in, no se incluye el servicio de limpieza. Las zonas comunes y la habitaci\u00f3n ser\u00e1n limpiadas por los compa\u00f1eros de piso; <\/li><li><strong>Ropa de cama:<\/strong> Se proporcionan s\u00e1banas y toallas (no toallas de playa);<\/li><li><strong>Cocina:<\/strong> Cocina totalmente equipada, de uso compartido;<\/li><li><strong>Comidas:<\/strong> Sin comidas;<\/li><li><strong>Internet:<\/strong> Mediante Wi-fi incluido;<\/li><li><strong>Llave:<\/strong> A recoger en la escuela a tu llegada (a cualquier hora, 24h\/d\u00eda);<\/li><li><strong>Edades:<\/strong> De 18 a 70 a\u00f1os aproximadamente, sexo mixto; <\/li><li><strong>Facturas:<\/strong> Incluidas (internet, agua, electricidad, etc.);<\/li><li><strong>Facturaci\u00f3n: <\/strong>Normalmente los domingos despu\u00e9s de las 18:00 (posibilidad de dejar el equipaje antes). Noches extra disponibles; <\/li><li><strong>Salida:<\/strong> Normalmente los s\u00e1bados antes de las 11:00 (posibilidad de dejar el equipaje para salidas posteriores). Noches extra disponibles. <\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-cd464d7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"cd464d7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-b546e80\" data-id=\"b546e80\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5ff3064 elementor-widget elementor-widget-video\" data-id=\"5ff3064\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/youtube.com\\\/shorts\\\/J_4wEquTilk?si=q-E2GJD5NDDlq7c0&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-a25ed29\" data-id=\"a25ed29\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8ffeaee elementor-widget elementor-widget-heading\" data-id=\"8ffeaee\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">San Vicente\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fc6453a color-scheme-inherit text-left elementor-widget elementor-widget-text-editor\" data-id=\"fc6453a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li><strong>ubicaci\u00f3n:<\/strong> M\u00e1ximo 5 minutos a pie de la escuela<\/li><li><strong>Tipos de habitaciones:<\/strong> 4x habitaciones individuales con cama grande, 2x habitaciones individuales con cama individual<\/li><li><strong>Cuarto de ba\u00f1o:<\/strong> 2 cuartos de ba\u00f1o compartidos, cada uno con ducha y WC<\/li><li><strong>Lavander\u00eda:<\/strong> Uso de lavadora incluido (detergentes propios)<\/li><li><strong>Limpieza:<\/strong> Limpieza de la habitaci\u00f3n al hacer el check-in, no se incluye servicio de limpieza. Las zonas comunes y la habitaci\u00f3n ser\u00e1n limpiadas por los compa\u00f1eros de piso <\/li><li><strong>Ropa de cama:<\/strong> Se proporcionan s\u00e1banas y toallas (no toallas de playa)<\/li><li><strong>Cocina:<\/strong> Cocina totalmente equipada, de uso compartido<\/li><li><strong>Comidas:<\/strong> Sin comidas<\/li><li><strong>Internet:<\/strong> V\u00eda Wi-fi incluida<\/li><li><strong>Llave:<\/strong> A recoger en la escuela a la llegada (a cualquier hora, 24h\/d\u00eda)<\/li><li><strong>Edades:<\/strong> De 18 a 70 a\u00f1os aproximadamente, sexo mixto <\/li><li><strong>Facturas:<\/strong> Incluidas (internet, agua, electricidad, etc.)<\/li><li><strong>Facturaci\u00f3n: <\/strong>Normalmente los domingos despu\u00e9s de las 18:00 (posibilidad de dejar el equipaje antes). Noches extra disponibles; <\/li><li><strong>Salida:<\/strong> Normalmente los s\u00e1bados antes de las 11:00 (posibilidad de dejar el equipaje para salidas posteriores). Noches extra disponibles. <\/li><li><strong>Distancia al aeropuerto:<\/strong> Aprox.10 minutos en taxi y 20 minutos en autob\u00fas<\/li><li><strong>Transporte p\u00fablico:<\/strong> Aprox. 15 minutos a pie hasta la estaci\u00f3n central de autobuses <\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f9ab0c5 elementor-section-full_width elementor-section-stretched elementor-section-height-default elementor-section-height-default\" data-id=\"f9ab0c5\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-de5764a\" data-id=\"de5764a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-df2509f elementor-widget elementor-widget-image-carousel\" data-id=\"df2509f\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;5&quot;,&quot;navigation&quot;:&quot;none&quot;,&quot;image_spacing_custom&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:5,&quot;sizes&quot;:[]},&quot;slides_to_show_mobile&quot;:&quot;2&quot;,&quot;autoplay_speed&quot;:3000,&quot;autoplay&quot;:&quot;yes&quot;,&quot;infinite&quot;:&quot;yes&quot;,&quot;speed&quot;:500,&quot;image_spacing_custom_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;image_spacing_custom_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Image Carousel\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 de 7\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/maxxinstitutes.com\/wp-content\/uploads\/2024\/10\/Apartment-2.jpg\" alt=\"Apartment-2\" title=\"\"><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 de 7\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/maxxinstitutes.com\/wp-content\/uploads\/2024\/10\/Apartment-4-1.jpg\" alt=\"Apartment-4 (1)\" title=\"\"><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 de 7\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/maxxinstitutes.com\/wp-content\/uploads\/2024\/10\/Apartment-5.jpg\" alt=\"Apartment-5\" title=\"\"><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 de 7\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/maxxinstitutes.com\/wp-content\/uploads\/2024\/10\/Apartment-8.jpg\" alt=\"Apartment-8\" title=\"\"><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 de 7\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/maxxinstitutes.com\/wp-content\/uploads\/2024\/10\/Apartment-9.jpg\" alt=\"Apartment-9\" title=\"\"><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 de 7\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/maxxinstitutes.com\/wp-content\/uploads\/2024\/10\/Apartment-10.jpg\" alt=\"Apartment-10\" title=\"\"><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"7 de 7\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/maxxinstitutes.com\/wp-content\/uploads\/2024\/10\/Apartment-11.jpg\" alt=\"Apartment-11\" title=\"\"><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Apartamentos compartidos para estudiantes Si prefieres un estilo de vida independiente y quieres sumergirte de lleno en la vida estudiantil,<\/p>\n","protected":false},"author":5,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"two_page_speed":[],"footnotes":""},"class_list":["post-14605","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/maxxinstitutes.com\/es\/wp-json\/wp\/v2\/pages\/14605","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/maxxinstitutes.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/maxxinstitutes.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/maxxinstitutes.com\/es\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/maxxinstitutes.com\/es\/wp-json\/wp\/v2\/comments?post=14605"}],"version-history":[{"count":6,"href":"https:\/\/maxxinstitutes.com\/es\/wp-json\/wp\/v2\/pages\/14605\/revisions"}],"predecessor-version":[{"id":25941,"href":"https:\/\/maxxinstitutes.com\/es\/wp-json\/wp\/v2\/pages\/14605\/revisions\/25941"}],"wp:attachment":[{"href":"https:\/\/maxxinstitutes.com\/es\/wp-json\/wp\/v2\/media?parent=14605"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}