{"id":14635,"date":"2024-09-06T21:18:37","date_gmt":"2024-09-06T21:18:37","guid":{"rendered":"http:\/\/maxxinstitutes.com\/datenschutzbestimmungen\/"},"modified":"2026-04-16T01:57:29","modified_gmt":"2026-04-16T01:57:29","slug":"datenschutzbestimmungen","status":"publish","type":"page","link":"https:\/\/maxxinstitutes.com\/de\/datenschutzbestimmungen\/","title":{"rendered":"Datenschutzbestimmungen"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"14635\" class=\"elementor elementor-14635 elementor-84\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-14ca0747 elementor-section-full_width elementor-section-stretched elementor-section-height-default elementor-section-height-default\" data-id=\"14ca0747\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b2848fd\" data-id=\"b2848fd\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-22233ad elementor-widget elementor-widget-heading\" data-id=\"22233ad\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Datenschutzbestimmungen<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2b02b88 color-scheme-inherit text-left elementor-widget elementor-widget-text-editor\" data-id=\"2b02b88\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Der Schutz Ihrer Privatsph\u00e4re und Ihrer pers\u00f6nlichen Daten wird von uns sehr ernst genommen.<\/p><p>Unser Ziel bei der Datenverarbeitung ist es, personenbezogene Daten nur dann zu verarbeiten, wenn diese Daten f\u00fcr die sinnvolle und wirtschaftliche Nutzung der Angebote in unserem Online-Shop relevant sind. Unsere Datenschutzpolitik steht im Einklang mit der Allgemeinen Datenschutzverordnung (GDPR). <\/p><p>In diesem Dokument informieren wir Sie ausf\u00fchrlich \u00fcber die Daten, die wir verarbeiten, wenn Sie unsere Website besuchen, sowie \u00fcber die Form, in der wir diese Daten verarbeiten. Damit kommen wir unserer Informationspflicht gegen\u00fcber Ihnen gem\u00e4\u00df Art. 13 der GDPR. <\/p><p><strong>Verantwortliche Person und Kontaktangaben zum Datenschutzbeauftragten:<\/strong><\/p><p>Der Verantwortliche f\u00fcr die Datenverarbeitung, die auf unserer Website stattfindet, ist:<br>Instituto de Idiomas Ibiza SL<br>Avenida Ignacio Wallis 32<br>07800 Ibiza<br>Espa\u00f1a<\/p><p>Unseren Datenschutzbeauftragten erreichen Sie unter:<br>E-Mail: info@ii-ibiza.com<\/p><h3 class=\"margin-xl-top margin-l-bottom\">1. Pers\u00f6nliche Daten<\/h3><p>Gem\u00e4\u00df der DSGVO sind personenbezogene Daten &#8222;alle Informationen \u00fcber eine bestimmte oder bestimmbare nat\u00fcrliche Person (&#8218;betroffene Person&#8216;); als bestimmbar wird eine nat\u00fcrliche Person angesehen, die direkt oder indirekt identifiziert werden kann, insbesondere durch Zuordnung zu einer Kennung wie einem Namen, zu einer Kennnummer, zu Standortdaten, zu einer Online-Kennung oder zu einem oder mehreren besonderen Merkmalen, die Ausdruck der physischen, physiologischen, genetischen, psychischen, wirtschaftlichen, kulturellen oder sozialen Identit\u00e4t dieser nat\u00fcrlichen Person sind&#8220;.<\/p><h3 class=\"margin-xl-top margin-l-bottom\">2. Funktionen unserer Website<\/h3><p>In den folgenden Abschnitten erl\u00e4utern wir, welche Daten wir verarbeiten, wenn Sie die von uns angebotenen Funktionen nutzen. Au\u00dferdem erl\u00e4utern wir die Rechtsgrundlage f\u00fcr die Verarbeitung dieser Daten, wie lange wir Ihre Daten speichern und welche anderen Parteien Ihre Daten ggf. erhalten. <\/p><h4 class=\"margin-l-top margin-default-bottom\">a) Allgemeine Nutzung unserer Website<\/h4><p>Wenn Sie unsere Website besuchen, erfassen und speichern wir in der Regel nur pers\u00f6nliche Daten, die Sie uns aktiv zur Verf\u00fcgung stellen. Der Webservice unseres Hosts zeichnet jedoch auch automatisch Besuche auf unserer Website auf, insbesondere die IP-Adresse der Person, die die Website besucht. Ihre IP-Adresse wird nicht gespeichert.  <\/p><p>Um die Systemsicherheit aufrechtzuerhalten, erstellt unser Host auch Protokolldateien. Diese Protokolldateien enthalten Informationen wie z.B.: Das Datum des Zugriffs, die URL, der aufgerufene Inhalt und die \u00fcbertragenen Informationen. <\/p><p>Diese Informationen stehen uns nur in anonymisierter Form zur Verf\u00fcgung und k\u00f6nnen daher nicht auf einzelne Personen zur\u00fcckgef\u00fchrt werden.<\/p><p>Ihre IP-Adresse wird verarbeitet, um eine Verbindung herzustellen, die es uns erm\u00f6glicht, Ihnen den Zugang zu unserer Website zu erm\u00f6glichen, in \u00dcbereinstimmung mit Art. 6, para. 1(f) der GDPR. Dieser Zweck wird als berechtigtes Interesse eingestuft.  <\/p><p>Unsere Protokolldateien werden 30 Tage lang gespeichert.<\/p><h4 class=\"margin-l-top margin-default-bottom\">b) Kontakt-Formular<\/h4><p>Wir stellen Ihnen ein Formular zur Verf\u00fcgung, mit dem Sie mit uns Kontakt aufnehmen k\u00f6nnen. Um dieses Formular zu verwenden, m\u00fcssen Sie Ihre E-Mail-Adresse angeben, damit wir auf Ihre Anfrage antworten k\u00f6nnen. Sie k\u00f6nnen auch Ihren Namen, einen Betreff f\u00fcr Ihre Anfrage und die Details der Anfrage selbst angeben.  <\/p><p>Wenn Sie uns \u00fcber die auf unserer Website angegebene E-Mail-Adresse kontaktieren, erhalten wir Ihre E-Mail-Adresse und alle anderen Informationen, die Sie in Ihrer E-Mail angeben. Damit wir Ihre Anfrage bearbeiten k\u00f6nnen, sind wir verpflichtet, diese Daten zu verarbeiten. Wenn Sie mit uns Kontakt aufnehmen, verarbeiten wir Ihre Daten, damit wir Ihre Anfrage pr\u00fcfen und beantworten k\u00f6nnen. Die Rechtsgrundlage f\u00fcr die Verarbeitung dieser Daten ist Art. 6, Absatz. 1(f) der GDPR. Der vorgenannte Zweck wird als berechtigtes Interesse eingestuft.     <\/p><p>Wir speichern Ihre E-Mails und andere Korrespondenz mit uns so lange, wie es f\u00fcr die Bearbeitung Ihrer Anfrage erforderlich ist, plus einen weiteren Zeitraum von drei Jahren, f\u00fcr den Fall, dass Sie uns erneut mit Bezug auf Ihre urspr\u00fcngliche Frage kontaktieren. Dies gilt nicht, wenn der Inhalt Ihrer E-Mail eine vertragliche Beziehung mit uns begr\u00fcndet. In solchen F\u00e4llen richtet sich die Aufbewahrungsfrist nach dem Vertrag, auf den sich die E-Mail bezieht. Wir werden Ihnen gesondert erl\u00e4utern, wie Ihre Daten im Rahmen des jeweiligen Vertrages verarbeitet werden.   <\/p><h4 class=\"margin-l-top margin-default-bottom\">c) Er\u00f6ffnung eines Kundenkontos, Kauffunktion &amp; Bewertungen<\/h4><p>Wenn Sie ein Benutzerkonto er\u00f6ffnen, speichern wir die erforderlichen Benutzerdaten, die Sie freiwillig angeben. Wenn Sie eine Bestellung in unserem Online-Shop aufgeben, erstellen wir automatisch ein Benutzerkonto auf der Grundlage Ihrer Bestelldaten. Ihre Bestelldaten werden Ihnen per E-Mail zusammen mit einer Kopie unserer Allgemeinen Gesch\u00e4ftsbedingungen zugesandt. Als registrierter Benutzer k\u00f6nnen Sie Ihre Bestelldaten und fr\u00fchere Bestellungen jederzeit in Ihrem Benutzerkonto einsehen. Sie k\u00f6nnen uns jederzeit anweisen, Ihr Benutzerkonto zu l\u00f6schen. Wir verwenden die von Ihnen angegebenen Daten zur Erf\u00fcllung und Bearbeitung Ihrer Bestellung.     <\/p><p>Um ein Kundenkonto anzulegen und wenn Sie eine Bestellung bei uns aufgeben, erfassen wir die folgenden Daten: Ihre Anrede, Vorname(n), Nachname, E-Mail-Adresse, Passwort (nach Ihrer Wahl), Firma, Hausname\/Nummer, Stra\u00dfe und eventuelle zus\u00e4tzliche Adressdaten, Land, Postleitzahl, Region, Telefonnummer<\/p><p>Ihre Bewertungen sind auch mit Ihrem Kundenkonto verkn\u00fcpft. So k\u00f6nnen wir sicherstellen, dass Sie nur Produkte bewerten k\u00f6nnen, die Sie auch gekauft haben. Um diese Funktion bereitzustellen, erfassen wir die folgenden Daten: Ihren Namen, den Titel Ihrer Bewertung, Ihre Bewertung, Ihre Bewertung (Anzahl der Sterne). Wir werden zu keinem Zeitpunkt irgendwelche pers\u00f6nlichen Daten in Ihrem Konto ver\u00f6ffentlichen. Die Daten Ihres Kundenkontos werden ausschlie\u00dflich verarbeitet, um Ihnen die Funktionen des Kundenkontos zur Verf\u00fcgung zu stellen und &#8211; falls Sie einen Kauf t\u00e4tigen &#8211; um Ihre Bestellung zu bearbeiten und auszuf\u00fchren. Die Verarbeitung dieser Daten erfolgt auch auf der Grundlage von Art. 6, Absatz. 1(b) der GDPR. Dar\u00fcber hinaus sind wir gesetzlich verpflichtet, bestimmte Arten von Daten, wie Rechnungen, Vertr\u00e4ge und andere f\u00fcr unsere Buchhaltung relevante Informationen, f\u00fcr einen bestimmten Zeitraum zu speichern. Die Verarbeitung der Daten zu diesem Zweck erfolgt auf der Grundlage von Art. 6, Absatz. 1(c) der GDPR. Wir speichern die Daten, die im Zusammenhang mit Ihrem Kundenkonto verarbeitet werden, bis Sie Ihr Kundenkonto schlie\u00dfen. Nach der Schlie\u00dfung werden wir Ihre Daten f\u00fcr weitere drei Jahre speichern, f\u00fcr den Fall, dass sich aus Ihrem Rechtsverh\u00e4ltnis mit uns Anspr\u00fcche ergeben. Personenbezogene Daten, die in Vertr\u00e4gen oder Rechnungen enthalten sind, werden f\u00fcr einen Zeitraum von 11 Jahren ab dem Ende des Jahres, in dem Sie Ihr Konto geschlossen haben, gespeichert. Daten in der Gesch\u00e4ftskorrespondenz oder anderen Dokumenten, die f\u00fcr die Besteuerung relevant sind, werden f\u00fcr einen Zeitraum von sieben Jahren ab dem Ende des Jahres, in dem Sie Ihr Konto geschlossen haben, gespeichert.             <\/p><p>Im Rahmen der Vertragserf\u00fcllung werden wir Sie kontaktieren, um Sie einzuladen, die von Ihnen bestellten Produkte zu pr\u00fcfen. Die von Ihnen zur Verf\u00fcgung gestellten Informationen werden ausschlie\u00dflich f\u00fcr diesen Zweck verwendet und insbesondere nicht f\u00fcr Marketingzwecke genutzt oder an Dritte weitergegeben. Die Verarbeitung dieser Daten erfolgt auch auf der Grundlage von Art. 6, Absatz. 1(f) der Datenschutz-Grundverordnung verarbeitet; der vorgenannte Zweck wird als berechtigtes Interesse eingestuft. Wir werden Ihre Bewertung so lange speichern, wie wir das Produkt weiter verkaufen.    <\/p><p>Sofern Sie nichts anderes angegeben haben, verwenden wir die E-Mail-Adresse, die Sie beim Kauf unserer Waren oder Dienstleistungen angegeben haben, um Ihnen in elektronischer Form Werbung f\u00fcr Produkte oder Dienstleistungen zuzusenden, die denen \u00e4hnlich sind, die Sie zuvor gekauft haben. Sie k\u00f6nnen uns jederzeit auffordern, Ihre E-Mail-Adresse nicht mehr f\u00fcr diesen Zweck zu verwenden. Kontaktieren Sie uns dazu \u00fcber die in unserem Impressum angegebenen Kontaktdaten oder \u00fcber den in unseren Werbe-E-Mails angegebenen Link. Au\u00dfer den von Ihrem Telekommunikationsanbieter erhobenen Grundgeb\u00fchren entstehen Ihnen keine weiteren Kosten. Die Rechtsgrundlage f\u00fcr die Verarbeitung dieser Daten ist Art. 6, Absatz. 1(f) der GDPR und Art. 95 der GDPR . Wir speichern die f\u00fcr die Zusendung von Marketingmitteilungen erforderlichen Daten, bis Sie Ihre Zustimmung zur Zusendung von Marketingmitteilungen widerrufen.      <\/p><h4 class=\"margin-l-top margin-default-bottom\">d) Newsletter und Beratungsdienste<\/h4><p>Wenn Sie sich f\u00fcr unseren Newsletter anmelden, werden Ihre E-Mail-Adresse und Ihre Einwilligung gespeichert und ausschlie\u00dflich f\u00fcr eigene Werbezwecke genutzt, bis Sie den Bezug des Newsletters abbestellen. Sie k\u00f6nnen den Erhalt des Newsletters jederzeit abbestellen, wodurch Ihnen keine weiteren Kosten als die Kommunikationskosten auf Basis der Basistarife entstehen. <\/p><p>Als unser Kunde erhalten Sie einen kostenlosen Beratungsservice sowie Produktempfehlungen per E-Mail. Der Beratungsservice sowie die Produktempfehlungen werden jedem Kunden zur Verf\u00fcgung gestellt, egal ob er den Newsletter abonniert hat oder nicht. Auf diese Weise m\u00f6chten wir Sie \u00fcber alle unsere Produkte und Angebote informieren, die zu Ihrer Bestellhistorie passen und die Sie aufgrund Ihrer letzten Eink\u00e4ufe interessieren k\u00f6nnten. Selbstverst\u00e4ndlich halten wir uns dabei an die einschl\u00e4gigen gesetzlichen Bestimmungen. Sie k\u00f6nnen unseren Beratungsservice und unsere Produktempfehlungen jederzeit wieder abbestellen, ohne dass Ihnen daf\u00fcr andere Kosten als die Kommunikationskosten auf Basis der Grundgeb\u00fchren entstehen. Dazu m\u00fcssen Sie uns lediglich eine schriftliche Nachricht an die in Ziffer 13 genannten Kontaktdaten (z.B. E-Mail, Brief) senden. In jeder E-Mail, die Sie erhalten, finden Sie au\u00dferdem einen Link zur K\u00fcndigung.      <\/p><p>Wenn Sie sich f\u00fcr unseren Newsletter anmelden, wird Ihre E-Mail-Adresse und Ihre Einwilligung gespeichert und ausschlie\u00dflich f\u00fcr eigene Werbezwecke genutzt, bis Sie den Versand des Newsletters abbestellen. Dazu verwenden wir ein sogenanntes &#8222;Double Opt-In&#8220;-Verfahren, d.h. wir senden Ihnen unseren E-Mail-Newsletter nur dann zu, wenn Sie uns ausdr\u00fccklich mitgeteilt haben, dass Sie dies w\u00fcnschen. Wir senden Ihnen eine Best\u00e4tigungs-E-Mail, in der wir Sie bitten, auf den in dieser E-Mail enthaltenen Link zu klicken, \u00fcber den wir dann Ihre Best\u00e4tigung erhalten. Sie k\u00f6nnen den Newsletter jederzeit abbestellen, ohne dass Ihnen andere Kosten als die Kommunikationskosten auf Basis der Basistarife entstehen. Dazu m\u00fcssen Sie uns lediglich eine schriftliche Nachricht an die in Absatz 13 genannten Kontaktdaten (z.B. E-Mail, Brief) senden. Au\u00dferdem finden Sie in jedem Newsletter, den Sie erhalten, einen Link zur Abmeldung.     <\/p><p>Die Verarbeitung erfolgt auf der Grundlage von Art. 6 Abs.. 1 lit. a) GDPR. Wir speichern Ihre Daten, bis Sie Ihre Einwilligung widerrufen.   <\/p><p>Wir verwenden die automatisch generierten Informationen sowie die Informationen, die Sie uns zur Verf\u00fcgung stellen, um Ihr Einkaufserlebnis st\u00e4ndig zu verbessern, Sie vor unerw\u00fcnschter Werbung zu sch\u00fctzen und unsere Angebote individuell auf Ihre Interessen abzustimmen. Dazu verwenden wir die Informationen ausschlie\u00dflich in pseudonymer Form, also zum Beispiel den Empfang und die Lesebest\u00e4tigung von E-Mails, Ihre Bestellhistorie, Datum und Uhrzeit Ihres Besuchs in unserem Online-Shop und die von Ihnen besuchten Produktseiten. Die Analyse und Auswertung dieser Informationen erm\u00f6glicht es uns, Ihnen auf Sie zugeschnittene Werbeangebote zu senden. Unser Ziel ist es, unsere Werbung n\u00fctzlicher und interessanter f\u00fcr Sie zu gestalten. Dabei m\u00f6chten wir verhindern, dass Sie unerw\u00fcnschte Werbung erhalten und Ihnen nur Dinge zusenden, die f\u00fcr Sie von Interesse sein k\u00f6nnten, z.B. in Form von Newslettern, E-Mails mit Produktempfehlungen, postalischer Werbung oder Brosch\u00fcren in Paketen. Wenn Sie keine personalisierte Werbung erhalten m\u00f6chten, k\u00f6nnen Sie jederzeit beantragen, diese vollst\u00e4ndig zu stoppen oder auf Ihre W\u00fcnsche zuzuschneiden, ohne dass Ihnen daf\u00fcr andere Kosten als die Kommunikationskosten auf Basis der Grundgeb\u00fchren entstehen. Dazu m\u00fcssen Sie uns lediglich eine schriftliche Mitteilung an die in Ziffer 13 genannten Kontaktdaten (z.B. E-Mail, Brief) senden.      <\/p><p>Die Verarbeitung erfolgt hier auf der Grundlage von Art. 6 Abs.. 1 lit. f) GDPR. Unser berechtigtes Interesse besteht darin, unsere Produkte zu bewerben. Wir speichern Ihre Daten zu diesem Zweck, bis Sie der Verwendung widersprechen.    <\/p><h4 class=\"margin-l-top margin-default-bottom\">e) PayPal<\/h4><p>Wir nutzen die Zahlungsdienstleister PayPal und Payone. Anbieter dieser Zahlungsdienste ist PayPal (Europe) S.\u00e0.r.l. et Cie, S.C.A., 22-24 Boulevard Royal, L-2449 Luxemburg (im Folgenden &#8222;PayPal&#8220; genannt). Wenn Sie sich daf\u00fcr entscheiden, eine Zahlung \u00fcber diese Zahlungsanbieter vorzunehmen, werden die von Ihnen angegebenen Zahlungsdaten an den jeweiligen Zahlungsanbieter gem\u00e4\u00df Art. 6, Absatz. 1(f) der GDPR an den jeweiligen Zahlungsanbieter weitergegeben. Es gilt als berechtigtes Interesse, unseren Kunden eine breite Palette an bequemen Zahlungsm\u00f6glichkeiten anzubieten. Weitere Informationen zur Datenverarbeitung bei PayPal und Payone finden Sie unter https:\/\/www.paypal.com\/de\/webapps\/mpp\/ua\/privacy-full.<\/p><h3 class=\"margin-xl-top margin-l-bottom\">3. Empf\u00e4nger der Daten<\/h3><p>Innerhalb unseres Unternehmens haben die Abteilungen, die an der Bearbeitung Ihrer Bestellungen und der Beantwortung Ihrer Anfragen beteiligt sind, Zugriff auf Ihre Daten. Wir greifen auch auf externe Dienstleister zur\u00fcck, wenn wir eine bestimmte Aktion oder einen bestimmten Prozess nicht selbst durchf\u00fchren k\u00f6nnen (oder nicht durchf\u00fchrbar sind). Bei diesen externen Dienstleistern handelt es sich haupts\u00e4chlich um Anbieter von IT- und Telekommunikationsdiensten.  <\/p><h3 class=\"margin-xl-top margin-l-bottom\">4. Rechte der betroffenen Personen<\/h3><p>Die Allgemeine Datenschutzverordnung garantiert Ihnen bestimmte Rechte, die Sie gegen uns geltend machen k\u00f6nnen, wenn es daf\u00fcr rechtliche Gr\u00fcnde gibt.<\/p><ul class=\"list-disc\"><li><strong>Art. 15 der DSGVO &#8211; Recht auf Auskunft durch die betroffene Person:<\/strong> Sie haben das Recht, von uns eine Best\u00e4tigung dar\u00fcber zu erhalten, ob Sie betreffende personenbezogene Daten verarbeitet werden oder nicht, und wenn dies der Fall ist, welche Daten verarbeitet werden und wie die Daten verarbeitet werden.<\/li><li><strong>Art. 16 der GDPR &#8211; Recht auf Berichtigung:<\/strong> Sie haben das Recht, von uns ohne unangemessene Verz\u00f6gerung die Berichtigung unrichtiger personenbezogener Daten \u00fcber Sie zu verlangen. Unter Ber\u00fccksichtigung der Zwecke der Verarbeitung haben Sie auch das Recht, unvollst\u00e4ndige personenbezogene Daten vervollst\u00e4ndigen zu lassen, auch durch eine erg\u00e4nzende Erkl\u00e4rung. <\/li><li><strong>Art. 17 der GDPR &#8211; Recht auf L\u00f6schung (&#8222;Recht auf Vergessenwerden&#8220;):<\/strong> Sie haben das Recht, von uns die L\u00f6schung der Sie betreffenden personenbezogenen Daten ohne unangemessene Verz\u00f6gerung zu verlangen. Bitte beachten Sie die unter Punkt II beschriebene Ausnahme.  4.<\/li><li><strong>Art. 18 der GDPR &#8211; Recht auf Einschr\u00e4nkung der Verarbeitung:<\/strong> Sie haben das Recht, von dem f\u00fcr die Verarbeitung Verantwortlichen die Einschr\u00e4nkung der Verarbeitung zu verlangen.<\/li><li><strong>Art. 20 der GDPR &#8211; Recht auf Daten\u00fcbertragbarkeit:<\/strong> Wenn wir Ihre Daten auf der Grundlage Ihrer Einwilligung oder zur Erf\u00fcllung eines Vertrags verarbeiten, haben Sie das Recht, die Sie betreffenden personenbezogenen Daten, die Sie uns zur Verf\u00fcgung gestellt haben, in einem strukturierten, g\u00e4ngigen und maschinenlesbaren Format zu erhalten, und Sie haben das Recht, diese Daten ohne Behinderung durch uns an einen anderen Verantwortlichen zu \u00fcbermitteln oder die Daten an einen anderen Verantwortlichen \u00fcbermitteln zu lassen, entweder direkt oder indirekt und soweit dies technisch machbar ist.<\/li><li><strong>Art. 21 der GDPR &#8211; Recht auf Widerspruch:<\/strong> Sie haben das Recht, aus Gr\u00fcnden, die sich aus Ihrer besonderen Situation ergeben, jederzeit gegen die Verarbeitung Sie betreffender personenbezogener Daten, die auf unseren berechtigten Interessen beruhen oder im \u00f6ffentlichen Interesse bzw. in Aus\u00fcbung \u00f6ffentlicher Gewalt erforderlich sind, Widerspruch einzulegen.<br>Wenn Sie der Verarbeitung Ihrer personenbezogenen Daten widersprechen, werden wir Ihre personenbezogenen Daten nicht mehr verarbeiten, es sei denn, wir k\u00f6nnen zwingende Gr\u00fcnde f\u00fcr die Verarbeitung nachweisen, die Ihre Interessen, Rechte und Freiheiten \u00fcberwiegen, oder wenn wir Ihre Daten zur Geltendmachung, Aus\u00fcbung oder Verteidigung eines Rechtsanspruchs verarbeiten m\u00fcssen.<br>Wenn wir Ihre personenbezogenen Daten f\u00fcr Zwecke des Direktmarketings verarbeiten, haben Sie das Recht, einer solchen Verarbeitung Ihrer Daten jederzeit zu widersprechen. Wenn Sie der Verarbeitung Ihrer Daten f\u00fcr Zwecke des Direktmarketings widersprechen, werden wir Ihre personenbezogenen Daten nicht mehr f\u00fcr diesen Zweck verarbeiten. <\/li><li><strong>Art. 77 der Datenschutz-Grundverordnung &#8211; Recht auf Beschwerde bei einer Aufsichtsbeh\u00f6rde:<\/strong> Sie haben das Recht auf Beschwerde bei einer Aufsichtsbeh\u00f6rde, insbesondere in dem Mitgliedstaat Ihres gew\u00f6hnlichen Aufenthaltsorts, Ihres Arbeitsplatzes oder des Orts des mutma\u00dflichen Versto\u00dfes, wenn Sie der Ansicht sind, dass die Verarbeitung der Sie betreffenden personenbezogenen Daten gegen die geltenden Vorschriften verst\u00f6\u00dft.<\/li><\/ul><p>Wenn Sie Ihre Einwilligung erteilt haben, k\u00f6nnen Sie diese jederzeit widerrufen. In diesem Fall gilt die gesamte Datenverarbeitung, die vor dem Widerruf Ihrer Einwilligung stattgefunden hat, als rechtskonform. Um Ihre Einwilligung zu widerrufen, k\u00f6nnen Sie auf den in jeder E-Mail, die Sie von uns erhalten, enthaltenen Link klicken, um sich von unserem E-Mail-Service abzumelden. Sie k\u00f6nnen auch die entsprechende Einstellung in Ihrem Benutzerkonto \u00e4ndern oder eine E-Mail an info@maxxinstitutes.com senden. Wenn Sie uns eine Nachricht senden, in der Sie angeben, dass Sie keine E-Mails mehr von uns erhalten m\u00f6chten, werden wir keine weiteren E-Mails an die von Ihnen angegebene E-Mail-Adresse senden.    <\/p><h3 class=\"margin-xl-top margin-l-bottom\">5. Verpflichtung zur Bereitstellung von Daten<\/h3><p>Sie sind weder vertraglich noch gesetzlich verpflichtet, uns Ihre pers\u00f6nlichen Daten zur Verf\u00fcgung zu stellen. Ohne die von Ihnen zur Verf\u00fcgung gestellten Daten k\u00f6nnen wir Ihnen jedoch unsere Dienstleistungen nicht anbieten. <\/p><h3 class=\"margin-xl-top margin-l-bottom\">6. Vorhandensein von Systemen zur automatischen Entscheidungsfindung (einschlie\u00dflich Profiling)<\/h3><p>Wir verwenden keine automatischen Entscheidungsfindungssysteme, die rechtliche oder andere Auswirkungen auf Sie haben.<\/p><h3 class=\"margin-xl-top margin-l-bottom\">7. Internet-spezifische Datenverarbeitung<\/h3><p>Wir verwenden &#8222;Cookies&#8220;, um die Funktionalit\u00e4t unserer Internetseite zu verbessern und ihre Nutzung f\u00fcr Sie bequemer zu machen. Wenn Sie unsere Website besuchen, k\u00f6nnen diese &#8222;Cookies&#8220; verwendet werden, um Daten auf Ihrem Computer zu speichern. Sie k\u00f6nnen die Einstellungen Ihres Browsers so anpassen, dass die Speicherung von Cookies auf Ihrem Computer verhindert wird. Dies kann jedoch die Funktionalit\u00e4t unserer Website einschr\u00e4nken.   <\/p><p>Wenn Sie diese Website nutzen, werden Cookies auf Ihrem Computer gespeichert. Cookies sind kleine Textdateien, die in Verbindung mit der von Ihnen verwendeten Browsersoftware auf Ihrer Festplatte gespeichert werden und von denen die Stelle (in diesem Fall wir), die den Cookie setzt, bestimmte Informationen erh\u00e4lt. Cookies k\u00f6nnen keine Programme ausf\u00fchren oder Viren auf Ihren Computer \u00fcbertragen. Sie dienen lediglich dazu, das Internetangebot insgesamt nutzerfreundlicher und effektiver zu gestalten.   <\/p><p>a) Die Website verwendet Cookies in folgendem Umfang: Transiente Cookies (zur vor\u00fcbergehenden Nutzung), dauerhafte Cookies (zeitlich begrenzte Nutzung), Cookies von Dritten (von Dritten).<\/p><p>b) Transiente Cookies werden automatisch gel\u00f6scht, sobald Sie Ihren Browser schlie\u00dfen. Dazu geh\u00f6ren insbesondere die sogenannten Session-Cookies. Sie speichern eine sogenannte Session-ID, mit der verschiedene Anfragen Ihres Browsers einer gemeinsamen Sitzung zugeordnet werden k\u00f6nnen. So kann Ihr Computer wiedererkannt werden, wenn Sie die Website das n\u00e4chste Mal besuchen. Sitzungs-Cookies werden gel\u00f6scht, sobald Sie sich abmelden oder Ihren Browser schlie\u00dfen.    <\/p><p>c) Dauerhafte Cookies werden nach einer bestimmten Zeit, die von Cookie zu Cookie unterschiedlich sein kann, automatisch gel\u00f6scht. Sie haben die M\u00f6glichkeit, alle gespeicherten Cookies jederzeit \u00fcber die Einstellungsoptionen Ihres Browsers zu l\u00f6schen. <\/p><p>d) Sie k\u00f6nnen die Einstellungen Ihres Browsers nach Ihren W\u00fcnschen konfigurieren. Das bedeutet, dass Sie z.B. die Annahme von Drittanbieter-Cookies oder aller Cookies ablehnen k\u00f6nnen. Diese Einstellungsm\u00f6glichkeit kann jedoch dazu f\u00fchren, dass Sie nicht die volle Funktionalit\u00e4t dieser Website nutzen k\u00f6nnen. Sie k\u00f6nnen die Einstellungen Ihres Browsers auch so \u00e4ndern, dass Sie jedes Mal, wenn ein Cookie versucht, auf Ihren Computer zuzugreifen, um Ihre Zustimmung gebeten werden. Ausf\u00fchrliche Informationen dazu, wie Sie Ihre Browsereinstellungen \u00e4ndern k\u00f6nnen, finden Sie <a href=\"https:\/\/www.foodspring.es\/media\/wysiwyg\/PDFs\/Guide-to-Browser-Settings-for-Cookies-FS.pdf\" target=\"_blank\" rel=\"noopener\">in diesem Leitfaden<\/a>.    <\/p><h4 class=\"margin-l-top margin-default-bottom\">Google Analytics<\/h4><p>Google LLC (&#8222;Google&#8220;), 1600 Amphitheatre Parkway, Mountain View, CA 94043 USA<\/p><p>Wir verwenden Google Analytics auf unserer Website. Google Analytics ist ein Webanalysedienst, der die Nutzung unserer Website optimiert. Die IP-Adresse, die von Ihrem Browser durch die Nutzung von Google Analytics \u00fcbermittelt wird, wird nicht mit anderen Daten von Google kombiniert. Im Rahmen des Tracking-Systems von Google werden auch Informationen \u00fcber Produkte, die Sie bestellt haben, \u00fcbermittelt.   <\/p><p>Die von uns gesendeten und mit Cookies, Benutzer-IDs und Werbe-IDs verbundenen Daten werden nach 36 Monaten automatisch gel\u00f6scht. Weitere Informationen zu den Nutzungsbedingungen und Datenschutzrichtlinien finden Sie unter <a href=\"https:\/\/www.google.com\/analytics\/terms\/de.html\" target=\"_blank\" rel=\"noopener\">https:\/\/www.google.com\/analytics\/terms\/de.html<\/a> und <a href=\"https:\/\/policies.google.com\/?hl=de\" target=\"_blank\" rel=\"noopener\">https:\/\/policies.google.com\/?hl=de.<\/a> <\/p><p>Die Rechtsgrundlage f\u00fcr die Nutzung von Google Analytics ist Art. 6, Absatz. 1(f) der GDPR. <\/p><p>Mit dem folgenden Plugin k\u00f6nnen Sie das Google-Tracking deaktivieren: <a href=\"http:\/\/tools.google.com\/dlpage\/gaoptout?hl=de\" target=\"_blank\" rel=\"noopener\">http:\/\/tools.google.com\/dlpage\/gaoptout?hl=d<\/a><\/p><h4 class=\"margin-l-top margin-default-bottom\">Google Maps<\/h4><p>Google LLC (&#8222;Google&#8220;), 1600 Amphitheatre Parkway, Mountain View, CA 94043 USA<\/p><p>Wir verwenden den Kartendienst Google Maps auf unserer Website. Google Maps bietet eine Option zur Adressvervollst\u00e4ndigung, um sicherzustellen, dass Ihre Adresse korrekt ist. <\/p><p>Weitere Informationen zu den Nutzungsbedingungen und Datenschutzrichtlinien finden Sie unter <a href=\"https:\/\/www.google.com\/intl\/de_de\/help\/terms_maps.html\" target=\"_blank\" rel=\"noopener\">https:\/\/www.google.com\/intl\/de_de\/help\/terms_maps.html<\/a> und <a href=\"https:\/\/policies.google.com\/?hl=de\" target=\"_blank\" rel=\"noopener\">https:\/\/policies.google.com\/?hl=de.<\/a><\/p><p>Die Rechtsgrundlage f\u00fcr die Nutzung von Google Maps ist Art. 6, Absatz. 1(f) der GDPR. <\/p><h4 class=\"margin-l-top margin-default-bottom\">Facebook<\/h4><p>Facebook Inc., 1601 South California Avenue, Palo Alto, CA 94304 USA<\/p><p>Diese Website nutzt die von Facebook bereitgestellte Remarketing-Funktion &#8222;Custom Audiences&#8220;. Diese Funktion dient dazu, Facebook-Nutzern, die unsere Website besucht haben, gezielte Werbung anzuzeigen (&#8222;Facebook-Anzeigen&#8220;). Zu diesem Zweck wird die Tatsache, dass Sie diese Website besucht haben, an den Facebook-Server \u00fcbermittelt; Facebook verkn\u00fcpft diese Informationen dann mit Ihrem pers\u00f6nlichen Benutzerkonto.  <\/p><p>Weitere Informationen finden Sie unter: <a href=\"https:\/\/www.facebook.com\/about\/privacy\/\" target=\"_blank\" rel=\"noopener\">https:\/\/www.facebook.com\/about\/privacy\/<\/a><\/p><p>Die Nutzung dieses Dienstes erfolgt auf der Grundlage von Art. 6, Absatz. 1(f) der GDPR. Der vorgenannte Zweck wird als berechtigtes Interesse eingestuft.  <\/p><p>Klicken Sie <a href=\"https:\/\/www.foodspring.es\/en\/privacy-policy#\" target=\"_blank\" rel=\"noopener\">hier<\/a>, um Ihre Zustimmung zur Nutzung dieses Dienstes zu widerrufen.<\/p><h4 class=\"margin-l-top margin-default-bottom\">Google AdWords<\/h4><p>Google LLC (&#8222;Google&#8220;), 1600 Amphitheatre Parkway, Mountain View, CA 94043 USA<\/p><p>Unsere Website verwendet Google AdWords. AdWords ist ein Online-Werbeprogramm. Wir verwenden Conversion Tracking als Teil dieses Programms. Wenn Sie auf eine von Google gehostete Anzeige klicken, wird ein Cookie f\u00fcr das Conversion-Tracking auf Ihrem System abgelegt. Anhand des Cookies k\u00f6nnen wir und Google erkennen, dass Sie auf die Anzeige geklickt haben und zu unserer Website weitergeleitet wurden. Conversion-Cookies werden verwendet, um Conversion-Statistiken f\u00fcr AdWords-Kunden zu erstellen, die Conversion-Tracking nutzen.     <\/p><p>Weitere Informationen finden Sie unter: <a href=\"https:\/\/www.google.de\/policies\/privacy\/\" target=\"_blank\" rel=\"noopener\">https:\/\/www.google.de\/policies\/privacy\/<\/a><\/p><p>Die Nutzung dieses Dienstes erfolgt auf der Grundlage von Art. 6, Absatz. 1(f) der GDPR. Der vorgenannte Zweck wird als berechtigtes Interesse eingestuft.  <\/p><p>Klicken Sie <a href=\"https:\/\/www.foodspring.es\/en\/privacy-policy#\" target=\"_blank\" rel=\"noopener\">hier<\/a>, um Ihre Zustimmung zur Nutzung dieses Dienstes zu widerrufen.<\/p><h4 class=\"margin-l-top margin-default-bottom\">LinkedIn<\/h4><p>LinkedIn Corporation \u00a9 2019 (&#8222;LinkedIn&#8220;) 1000 W. Maude Ave, Sunnyvale, CA 94085<\/p><p>Durch LinkedIns Funktionen f\u00fcr Conversion-Tracking und Website-Demografie k\u00f6nnen wir verstehen, was passiert, nachdem ein LinkedIn-Nutzer auf unsere Anzeige geklickt hat, indem wir von LinkedIn bereitgestellte Analysemethoden und -systeme (z. B. Insight-Tags, Pixel und APIs) verwenden, die es uns erm\u00f6glichen, Daten \u00fcber Aktionen, die Personen auf unseren Websites ausf\u00fchren, an LinkedIn und seine Partner zu senden (&#8222;Ereignisdaten&#8220;).<\/p><p>Durch LinkedIn Matched Audiences und die damit verbundenen Datenintegrationen k\u00f6nnen wir Anzeigen auf Zielgruppen ausrichten, die auf Daten basieren, die wir LinkedIn zur Verf\u00fcgung stellen, entweder direkt oder in unserem Namen durch einen autorisierten Dritten. Informationen \u00fcber Ihre Identit\u00e4t werden nicht gespeichert. <\/p><p>Weitere Informationen zu den Nutzungsbedingungen und Datenschutzrichtlinien finden Sie unter <a href=\"https:\/\/www.linkedin.com\/legal\/privacy-policy\" target=\"_blank\" rel=\"noopener\">https:\/\/www.linkedin.com\/legal\/privacy-policy<\/a><\/p><p>Die Nutzung dieses Dienstes erfolgt auf der Grundlage von Art. 6, Absatz. 1(f) der GDPR. Der vorgenannte Zweck wird als berechtigtes Interesse eingestuft.  <\/p><p>Sie k\u00f6nnen Ihre Zustimmung zur Nutzung dieses Dienstes unter den folgenden Links widerrufen, die Sie in Abschnitt 2.4 der Datenschutzerkl\u00e4rung finden: <a href=\"https:\/\/www.linkedin.com\/legal\/privacy-policy\" target=\"_blank\" rel=\"noopener\">https:\/\/www.linkedin.com\/legal\/privacy-policy<\/a><\/p><p><span style=\"font-family: Poppins, Arial, Helvetica, sans-serif; font-size: 22px; font-style: normal; font-weight: 600; color: #242424;\">8. Datenverarbeitung auf Plattformen sozialer Medien<\/span><\/p><p>Wir unterhalten Profile in verschiedenen sozialen Netzwerken, \u00fcber die Sie mit uns in Kontakt treten k\u00f6nnen. Derzeit sind dies die Netzwerke Facebook, Instagram, Youtube, Pinterest und WhatsApp. Grunds\u00e4tzlich ist nur der jeweilige Betreiber des Netzwerks datenschutzrechtlich verantwortlich f\u00fcr alle Verarbeitungen personenbezogener Daten, die dort stattfinden, zum Beispiel wenn Sie ein Profil besuchen oder einen Kommentar hinterlassen. Wir selbst haben keine Kenntnis von den durch den jeweiligen Betreiber verarbeiteten Daten oder von den einzelnen Datenverarbeitungsvorg\u00e4ngen, die der Betreiber durchf\u00fchrt. Diese Informationen werden nicht in einem individualisierten Format an uns weitergegeben. In diesem Zusammenhang k\u00f6nnen wir, wie jeder andere Nutzer sozialer Netzwerke auch, nur auf die Informationen zugreifen, die Sie in Ihrem Profil ver\u00f6ffentlicht oder anderweitig zug\u00e4nglich gemacht haben. Ausf\u00fchrlichere Informationen \u00fcber die Datenverarbeitung, die in den einzelnen Netzwerken stattfindet, erhalten Sie unter den folgenden Adressen:      <\/p><ul><li>YouTube: <a href=\"https:\/\/policies.google.com\/privacy?hl=en\" target=\"_blank\" rel=\"noopener\">https:\/\/policies.google.com\/privacy?hl=en<\/a><\/li><li>Instagram: <a href=\"https:\/\/help.instagram.com\/519522125107875\/?helpref=hc_fnav&amp;bc%5B0%5D=Instagram%20Help&amp;bc%5B1%5D=Privacy%20and%20Safety%20Center\" target=\"_blank\" rel=\"noopener\">https:\/\/help.instagram.com\/519522125107875\/?helpref=hc_fnav&amp;bc[0]=Instagram%20Hilfe&amp;bc[1]=Datenschutz%20und%20Safety%20Zentrum<\/a><\/li><li>WhatsApp: <a href=\"https:\/\/www.whatsapp.com\/legal\/#privacy-policy\" target=\"_blank\" rel=\"noopener\">https:\/\/www.whatsapp.com\/legal\/#privacy-policy<\/a><\/li><\/ul><p>Sie stellen uns jedoch pers\u00f6nliche Daten zur Verf\u00fcgung, wenn Sie uns eine Nachricht senden oder einen Beitrag auf unserer Website hinterlassen. Wir verwenden diese pers\u00f6nlichen Daten, um auf Ihre Nachricht zu antworten. Zu diesem Zweck k\u00f6nnen wir Ihre Nachricht aus dem betreffenden sozialen Netzwerk in unsere eigenen Verarbeitungssysteme importieren, damit wir effizienter und schneller antworten k\u00f6nnen. Aus diesem Grund nutzen wir m\u00f6glicherweise externe IT-Dienstleister, um auf Ihre Nachrichten zu antworten. Wir speichern Ihre Nachrichten so lange, wie es f\u00fcr die Bearbeitung Ihrer Anfrage erforderlich ist. Anschlie\u00dfend speichern wir sie f\u00fcr einen Zeitraum von 3 Jahren f\u00fcr den Fall, dass Sie uns erneut mit Bezug auf Ihre urspr\u00fcngliche Frage kontaktieren. Diese Zwecke stellen auch unser berechtigtes Interesse dar, zu dessen Gunsten wir diese Datenverarbeitung durchf\u00fchren. (Art. 6 Abs. 1 lit. f) DSG-VO). F\u00fcr die Datenverarbeitung auf unserer Facebook-Profilseite gelten besondere Bedingungen. Diese finden Sie in der separaten <a href=\"https:\/\/www.foodspring.es\/en\/privacy-policy-facebook\" target=\"_blank\" rel=\"noopener\">Facebook-Datenschutzrichtlinie<\/a>.          <\/p><h3 class=\"margin-xl-top margin-l-bottom\">10. Fragen und Kommentare<\/h3><p>Wir tun alles, was in unserer Macht steht, um die Sicherheit Ihrer Daten zu sch\u00fctzen und zu wahren. Bitte z\u00f6gern Sie nicht, uns zu kontaktieren, wenn Sie Fragen oder Anmerkungen zu unserer Datenschutzpolitik haben. Bei Fragen zur Erhebung, Verarbeitung oder Nutzung Ihrer personenbezogenen Daten, bei Ausk\u00fcnften, Berichtigung, Sperrung oder L\u00f6schung von Daten sowie bei Widerruf erteilter Einwilligungen wenden Sie sich bitte an: info@ii-ibiza.cominf  <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Datenschutzbestimmungen Der Schutz Ihrer Privatsph\u00e4re und Ihrer pers\u00f6nlichen Daten wird von uns sehr ernst genommen. Unser Ziel bei der Datenverarbeitung<\/p>\n","protected":false},"author":5,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"two_page_speed":[],"footnotes":""},"class_list":["post-14635","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/maxxinstitutes.com\/de\/wp-json\/wp\/v2\/pages\/14635","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/maxxinstitutes.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/maxxinstitutes.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/maxxinstitutes.com\/de\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/maxxinstitutes.com\/de\/wp-json\/wp\/v2\/comments?post=14635"}],"version-history":[{"count":2,"href":"https:\/\/maxxinstitutes.com\/de\/wp-json\/wp\/v2\/pages\/14635\/revisions"}],"predecessor-version":[{"id":28032,"href":"https:\/\/maxxinstitutes.com\/de\/wp-json\/wp\/v2\/pages\/14635\/revisions\/28032"}],"wp:attachment":[{"href":"https:\/\/maxxinstitutes.com\/de\/wp-json\/wp\/v2\/media?parent=14635"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}